{"id":1862,"date":"2013-12-16T09:57:42","date_gmt":"2013-12-16T07:57:42","guid":{"rendered":"https:\/\/c-potou.com\/page-daccueil\/"},"modified":"2024-04-30T18:13:36","modified_gmt":"2024-04-30T15:13:36","slug":"page-daccueil","status":"publish","type":"page","link":"https:\/\/c-potou.com\/fr\/","title":{"rendered":"Page d&rsquo;accueil"},"content":{"rendered":"\n<div class=\"slider-wrapper relative hide-for-small\" id=\"slider-637593617\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-1383596739\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"583\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/main_photo-1400x800.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-2126672844\" class=\"text-box banner-layer x50 md-x95 lg-x95 y50 md-y10 lg-y10 res-text\">\n              <div data-parallax=\"-1\" data-parallax-fade=\"true\">       <div data-animate=\"bounceIn\">           <div class=\"text-box-content text dark text-shadow-5\">\n              \n              <div class=\"text-inner text-right\">\n                  \n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1807467110\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"194\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_monogram_trans_white.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1807467110 {\n  width: 17%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"alt-font\"><span style=\"font-size: 160%; display: none;\">Constantine Potou<\/span><\/p>\r\n\r\n<h2 class=\"uppercase\"><strong><span style=\"font-size: 80%; font-weight: 300;\" data-line-height=\"xs\">LA HAUTE QUALIT\u00c9\r\nRENCONTRE LE D\u00c9LICIEUX!<\/span><\/strong><\/h2>\r\n\t<div id=\"gap-2028046760\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2028046760 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\r\n<h3 class=\"lead uppercase\" style=\"font-size: 140%; font-weight: 300; line-height: 1.2;\"><em>\u00ab\u00a0La mer d&rsquo; oliiviers\u00a0\u00bb<\/em><\/h3>\n<a class=\"button primary hidden\" style=\"border-radius:99px;\">\n\t\t<span>Shop Now<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-2126672844 {\n  width: 80%;\n}\n#text-box-2126672844 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2126672844 {\n    width: 34%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1383596739 {\n  padding-top: 100%;\n}\n#banner-1383596739 .overlay {\n  background-color: rgba(0, 0, 0, 0.1);\n}\n#banner-1383596739 .banner-bg img {\n  object-position: 68% 27%;\n}\n@media (min-width:550px) {\n  #banner-1383596739 {\n    padding-top: 100%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"slider-wrapper relative show-for-small\" id=\"slider-833769214\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-897819748\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"583\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/main_photo-1400x800.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-983265875\" class=\"text-box banner-layer x50 md-x95 lg-x95 y10 md-y0 lg-y0 res-text\">\n              <div data-parallax=\"-1\" data-parallax-fade=\"true\">       <div data-animate=\"bounceIn\">           <div class=\"text-box-content text dark text-shadow-5\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_345662758\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"194\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_monogram_trans_white.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_345662758 {\n  width: 17%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"alt-font\"><span style=\"font-size: 160%; display: none;\">Constantine Potou<\/span><\/p>\r\n\r\n<h2 class=\"uppercase\"><strong><span style=\"font-size: 80%; font-weight: 300;\" data-line-height=\"xs\">LA HAUTE QUALIT\u00c9\r\nRENCONTRE LE D\u00c9LICIEUX!<\/span><\/strong><\/h2>\r\n\t<div id=\"gap-1281727448\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1281727448 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\r\n<h3 class=\"lead uppercase\" style=\"font-size: 140%; font-weight: 300; line-height: 1.2;\"><em>\u00ab\u00a0La mer d&rsquo; oliiviers\u00a0\u00bb<\/em><\/h3>\n<a class=\"button primary hidden\" style=\"border-radius:99px;\">\n\t\t<span>Shop Now<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-983265875 {\n  width: 80%;\n}\n#text-box-983265875 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-983265875 {\n    width: 34%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-897819748 {\n  padding-top: 100%;\n}\n#banner-897819748 .overlay {\n  background-color: rgba(0, 0, 0, 0.2);\n}\n#banner-897819748 .banner-bg img {\n  object-position: 68% 27%;\n}\n@media (min-width:550px) {\n  #banner-897819748 {\n    padding-top: 100%;\n  }\n  #banner-897819748 .overlay {\n    background-color: rgba(0, 0, 0, 0.4);\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"row align-middle align-center\"  id=\"row-692445858\">\n\n\n\t<div id=\"col-1069213608\" class=\"col hide-for-small medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1555248910\">\n\t\t\t\t<div data-parallax-fade=\"true\" data-parallax=\"7\">\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"530\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right.png 300w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right-226x400.png 226w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t\n<style>\n#image_1555248910 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-578602184\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Qui nous sommes<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n\nLe groupe de soci\u00e9t\u00e9s Constantin Potou produit, s\u00e9lectionne, standardise selon son propre cahier des charges, ma\u00eetrisant l&rsquo;ensemble du processus de d\u00e9veloppement, de collecte, de transport et de standardisation des produits. Tout cela est r\u00e9alis\u00e9 avec l&rsquo;\u00e9thique ultime, le respect envers le produit, la nature et l&rsquo;environnement ainsi qu&rsquo;avec une sensibilit\u00e9 sociale au facteur humain.\n<a href=\"https:\/\/c-potou.com\/fr\/a-propos-de-nous\/\" class=\"button primary is-outline lowercase\">\n\t\t<span>D\u00e9couvrez Constantin Potou<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-578602184 > .col-inner {\n  padding: 0px 0px 50px 0px;\n  margin: 100px 0px 50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1033792298\" class=\"col hide-for-small medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_997420089\">\n\t\t\t\t<div data-parallax-fade=\"true\" data-parallax=\"7\">\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"530\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right-1.png 300w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/03\/potou_logo_right-1-226x400.png 226w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t\n<style>\n#image_997420089 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_1057359554\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >La qualit\u00e9 sup\u00e9rieure<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<div class=\"row row-large align-middle align-center\"  id=\"row-2144679153\">\n\n\n\t<div id=\"col-1310856352\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1224130646\" class=\"text\">\n\t\t\n\n&nbsp;\r\n<h2>Huiles d&rsquo;olive Premium Potou<\/h2>\r\n<h3>signifie Great Taste, World Awards &amp; Health Claim Certification (EU 432\/2012)<\/h3>\r\nBon go\u00fbt, r\u00e9compenses mondiales et Certification d&rsquo; All\u00e9gations de Sant\u00e9\r\n\r\nLe monde entier glorifie l&rsquo; authentique huile d&rsquo;olive extra vierge grecque AOP de la vari\u00e9t\u00e9 Koroneiki de Kalamata. Cela se produit non seulement pour son go\u00fbt exquis, mais aussi pour ses nombreuses propri\u00e9t\u00e9s b\u00e9n\u00e9fiques, comme le montrent de nombreuses recherches.\r\n\r\nNotre vari\u00e9t\u00e9 Koroneiki a \u00e9t\u00e9 prouv\u00e9e \u00e0 partir d&rsquo;une \u00e9tude universitaire (Universit\u00e9 d&rsquo;Ath\u00e8nes, D\u00e9partement de Pharmacologie) qui est riche en polyph\u00e9nols, en particulier en elaiokanthali et elaiasini, qui ont une forte activit\u00e9 anti-inflammatoire comparable \u00e0 celle trouv\u00e9e dans les m\u00e9dicaments anti-inflammatoires classiques dans des cas tr\u00e8s fr\u00e9quents. utiliser.\n\t\t\n<style>\n#text-1224130646 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/fr\/boutique\/\" class=\"button primary is-outline\" >\n\t\t<span>Achetez ici<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1470717883\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_617073454\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1270\" height=\"1270\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21.jpg 1270w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-400x400.jpg 400w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-800x800.jpg 800w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-280x280.jpg 280w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-768x768.jpg 768w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-600x600.jpg 600w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-21-100x100.jpg 100w\" sizes=\"auto, (max-width: 1270px) 100vw, 1270px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_617073454 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1470717883 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1057359554 {\n  padding-top: 59px;\n  padding-bottom: 59px;\n  min-height: 800px;\n  background-color: rgb(202, 204, 165);\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<div class=\"container section-title-container\" style=\"margin-top:30px;\"><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Latest news<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns-1 slider row-slider slider-nav-circle\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/10\/title-french\/\" class=\"plain\" aria-label=\"Title french.\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-400x400.jpg 400w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-800x800.jpg 800w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-280x280.jpg 280w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-768x768.jpg 768w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-1536x1536.jpg 1536w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-2048x2048.jpg 2048w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-600x600.jpg 600w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/10\/title-french\/\" class=\"plain\">Title french.<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\twgergerwgwegre \u03b4\u03b3\u03c3\u03b4\u03b3\u03c3\u03b4\u03c6\u03b3\u03c3\u03b3\u03c3 \u03c3\u03b4\u03b3\u03c3\u03b4\u03b3\u03c3\u03b3\u03c3\u03b3\u03c6\u03b3\u03c6\u03b4\u03c6\u03b4\u03b3\u03b4\u03c6\u03b3\u03b4\u03b3\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/05\/cuisiner-avec-des-produits-aop-ert2-emission-nationale-de-television\/\" class=\"plain\" aria-label=\"\u00abCuisiner avec des produits AOP\u00bb. ERT2 \u00c9mission nationale de t\u00e9l\u00e9vision\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/ert21-224x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/ert21-224x400.jpg 224w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/ert21-449x800.jpg 449w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/ert21.jpg 715w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/05\/cuisiner-avec-des-produits-aop-ert2-emission-nationale-de-television\/\" class=\"plain\">\u00abCuisiner avec des produits AOP\u00bb. ERT2 \u00c9mission nationale de t\u00e9l\u00e9vision<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLe chef Manolis Papoutsakis et Konstantinos Potou pr\u00e9parent une d\u00e9licieuse soupe de poisson grecque appel\u00e9e [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">15<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mai<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/04\/constantin-potou-soutient-la-synergie-de-recherche-scientifique-avec-le-woch-world-olive-center-for-health\/\" class=\"plain\" aria-label=\"Constantin Potou soutient la synergie de recherche scientifique avec le WOCH (World Olive Center for Health)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"268\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/woch.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/woch.jpg 268w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/woch-100x100.jpg 100w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/04\/constantin-potou-soutient-la-synergie-de-recherche-scientifique-avec-le-woch-world-olive-center-for-health\/\" class=\"plain\">Constantin Potou soutient la synergie de recherche scientifique avec le WOCH (World Olive Center for Health)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLe Centre ol\u00e9icole mondial \u00e0 but non lucratif a pour objectif principal l&rsquo;argent qu&rsquo;il recevra [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Avr<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/04\/quest-ce-que-lhuile-dolive-hautement-phenolique\/\" class=\"plain\" aria-label=\"Qu&rsquo;est-ce que l&rsquo;huile d&rsquo;olive hautement ph\u00e9nolique?\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"581\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-581x400.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-581x400.png 581w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-800x550.png 800w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-1163x800.png 1163w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-768x528.png 768w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM-1536x1057.png 1536w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/04\/Screenshot-2021-04-13-at-11.38.59-PM.png 1788w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/04\/quest-ce-que-lhuile-dolive-hautement-phenolique\/\" class=\"plain\">Qu&rsquo;est-ce que l&rsquo;huile d&rsquo;olive hautement ph\u00e9nolique?<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Avr<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/01\/say-greece-portal-talks-about-us-thank-you\/\" class=\"plain\" aria-label=\"\u00a0\u00bbSay Greece\u00a0\u00bb portal talks about us! Thank you!\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"360\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/20190608_121252-2-e1611532633492.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/01\/say-greece-portal-talks-about-us-thank-you\/\" class=\"plain\">\u00a0\u00bbSay Greece\u00a0\u00bb portal talks about us! Thank you!<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tContinuer la lecture: https:\/\/saygreece.org\/2021\/01\/28\/to-gnisio-elliniko-ladi-akouei-sto-onoma-constantin-potou\/\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">28<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/01\/suivez-nous-notre-passion-est-de-produire-de-lhuile-dolive-extra-vierge-de-haute-qualite\/\" class=\"plain\" aria-label=\"Suivez-nous. Notre passion est de produire de l&rsquo;huile d&rsquo;olive extra vierge de haute qualit\u00e9\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/potouv2-730x400.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/potouv2-730x400.png 730w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/potouv2-768x421.png 768w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/potouv2-800x438.png 800w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/potouv2.png 1394w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2021\/01\/suivez-nous-notre-passion-est-de-produire-de-lhuile-dolive-extra-vierge-de-haute-qualite\/\" class=\"plain\">Suivez-nous. Notre passion est de produire de l&rsquo;huile d&rsquo;olive extra vierge de haute qualit\u00e9<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">21<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2020\/11\/constantin-potou-est-membre-de-lalliance-pour-la-reduction-du-gaspillage-alimentaire\/\" class=\"plain\" aria-label=\"Constantin Potou est membre de l&rsquo;Alliance pour la R\u00e9duction du Gaspillage Alimentaire\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/SYMAXIA-LOGO_EN-401x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/SYMAXIA-LOGO_EN-401x400.jpg 401w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/SYMAXIA-LOGO_EN-280x280.jpg 280w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/SYMAXIA-LOGO_EN-100x100.jpg 100w, https:\/\/c-potou.com\/wp-content\/uploads\/2021\/05\/SYMAXIA-LOGO_EN.jpg 568w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2020\/11\/constantin-potou-est-membre-de-lalliance-pour-la-reduction-du-gaspillage-alimentaire\/\" class=\"plain\">Constantin Potou est membre de l&rsquo;Alliance pour la R\u00e9duction du Gaspillage Alimentaire<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tC&rsquo;est un grand plaisir et une grande fiert\u00e9 que nous ayons sign\u00e9 l&rsquo;\u00ab Accord de [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">21<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:53%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2020\/11\/constantin-potou-soutient-boroume-we-can\/\" class=\"plain\" aria-label=\"Constantin Potou soutient Boroume (\u00ab\u00a0We Can\u00a0\u00bb)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"400\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2022\/03\/member_diktyou_boroume_en-306x400.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2022\/03\/member_diktyou_boroume_en-306x400.png 306w, https:\/\/c-potou.com\/wp-content\/uploads\/2022\/03\/member_diktyou_boroume_en.png 586w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/c-potou.com\/fr\/2020\/11\/constantin-potou-soutient-boroume-we-can\/\" class=\"plain\">Constantin Potou soutient Boroume (\u00ab\u00a0We Can\u00a0\u00bb)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tBoroume (\u00ab We Can \u00bb) est une organisation \u00e0 but non lucratif dont la mission [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">21<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Browse products<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n  <style>\n    #cats-236669147 .grid-col-1{height: 600px}\n    #cats-236669147 .grid-col-1-2{height: 300px}\n    #cats-236669147 .grid-col-1-3{height:200px}\n    #cats-236669147 .grid-col-2-3{height: 400px}\n    #cats-236669147 .grid-col-1-4{height: 150px}\n    #cats-236669147 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #cats-236669147 .grid-col-1{height: 400px}\n      #cats-236669147 .grid-col-1-2{height: 200px}\n      #cats-236669147 .grid-col-1-3{height:133.33333333333px}\n      #cats-236669147 .grid-col-2-3{height: 266.66666666667px}\n      #cats-236669147 .grid-col-1-4{height: 100px}\n      #cats-236669147 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #cats-236669147 .grid-col-1{height: 400px}\n      #cats-236669147 .grid-col-1-2{height: 200px}\n      #cats-236669147 .grid-col-1-3{height:133.33333333333px}\n      #cats-236669147 .grid-col-2-3{height: 266.66666666667px}\n      #cats-236669147 .grid-col-1-4{height: 100px}\n      #cats-236669147 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"cats-236669147\" class=\"row row-small row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"product-category col grid-col grid-col-1 large-6 medium-12\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Acc\u00e9der \u00e0 la cat\u00e9gorie de produits Cadeaux d&#039;entreprise\" href=\"https:\/\/c-potou.com\/fr\/categorie-produit\/cadeaux-dentreprise\/\">                <div class=\"box box-category has-hover box-overlay dark box-text-middle \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/image001-20-400x400.jpg\" alt=\"Cadeaux d&#039;entreprise\" width=\"300\" height=\"300\" \/>                  <div class=\"overlay\" style=\"background-color: 1\"><\/div>                                    <\/div>\n                <\/div>\n                <div class=\"box-text text-center is-large\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Cadeaux d&#039;entreprise                      <\/h5>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col grid-col grid-col-1 large-3 medium-6\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Acc\u00e9der \u00e0 la cat\u00e9gorie de produits Huiles d&#039;olive Premium\" href=\"https:\/\/c-potou.com\/fr\/categorie-produit\/huiles-dolive-premium\/\">                <div class=\"box box-category has-hover box-overlay dark box-text-middle \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2553-1-400x400.jpg\" alt=\"Huiles d&#039;olive Premium\" width=\"300\" height=\"300\" \/>                  <div class=\"overlay\" style=\"background-color: 1\"><\/div>                                    <\/div>\n                <\/div>\n                <div class=\"box-text text-center is-large\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Huiles d&#039;olive Premium                      <\/h5>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col grid-col grid-col-1-2 large-3 medium-6\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Acc\u00e9der \u00e0 la cat\u00e9gorie de produits P\u00e2tes \u00e0 tartiner aux olives\" href=\"https:\/\/c-potou.com\/fr\/categorie-produit\/pates-a-tartiner-aux-olives\/\">                <div class=\"box box-category has-hover box-overlay dark box-text-middle \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/spread1.jpg\" alt=\"P\u00e2tes \u00e0 tartiner aux olives\" width=\"300\" height=\"300\" \/>                  <div class=\"overlay\" style=\"background-color: 1\"><\/div>                                    <\/div>\n                <\/div>\n                <div class=\"box-text text-center is-large\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              P\u00e2tes \u00e0 tartiner aux olives                      <\/h5>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col grid-col grid-col-1-2 large-3 medium-6\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Acc\u00e9der \u00e0 la cat\u00e9gorie de produits Olives\" href=\"https:\/\/c-potou.com\/fr\/categorie-produit\/olives-fr\/\">                <div class=\"box box-category has-hover box-overlay dark box-text-middle \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2021\/06\/DSC2569-1-scaled.jpg\" alt=\"Olives\" width=\"300\" height=\"300\" \/>                  <div class=\"overlay\" style=\"background-color: 1\"><\/div>                                    <\/div>\n                <\/div>\n                <div class=\"box-text text-center is-large\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Olives                      <\/h5>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><\/div>\n\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Our collaborations<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<div class=\"row row-small\"  id=\"row-1664921671\">\n\n\n\t<div id=\"col-1633366308\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" style=\"width:80%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/PAUL-LOGO.jpeg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/PAUL-LOGO.jpeg 200w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/PAUL-LOGO-100x100.jpeg 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                         <\/div>\n          <\/div>\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">PAUL Athens<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n\t\t\t\t\t\n\nPanepistimiou 10, Athens 10761\r\nTelephone +30 21 0363 2352\n\n                <\/div>\n          <\/div>\n    <\/div>\n\n\t\n    \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-725316688\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" style=\"width:80%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"750\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Le-Petit-Marchel.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Le-Petit-Marchel.jpg 1500w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Le-Petit-Marchel-800x400.jpg 800w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Le-Petit-Marchel-1400x700.jpg 1400w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Le-Petit-Marchel-768x384.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>                         <\/div>\n          <\/div>\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Le Petit Marcel<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n\t\t\t\t\t\n\n65 Rue Rambuteau, 75004 Paris France\r\nT\u00e9l\u00e9phone +33974640346\n\n                <\/div>\n          <\/div>\n    <\/div>\n\n\t\n    \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-658922969\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" style=\"width:80%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"800\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Gallina.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Gallina.jpg 1400w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Gallina-700x400.jpg 700w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Gallina-768x439.jpg 768w, https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/Gallina-800x457.jpg 800w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/>                         <\/div>\n          <\/div>\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Gallina Athens<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n\t\t\t\t\t\n\nMarkou Mpotsari 49, Athens 11742\r\nTelephone +302109237425\n\n\n                <\/div>\n          <\/div>\n    <\/div>\n\n\t\n    \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2054900295\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n    <div class=\"box has-hover has-hover box-text-bottom\" >\n\n                  <div class=\"box-image \" style=\"width:80%;\">\n           <div class=\"box-image-inner image-cover\" style=\"border-radius:100%;padding-top:100%;\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"132\" src=\"https:\/\/c-potou.com\/wp-content\/uploads\/2024\/04\/logoFLORA.png\" class=\"attachment- size-\" alt=\"\" \/>                         <\/div>\n          <\/div>\n         \n          <div class=\"box-text text-center\" >\n                <div class=\"box-text-inner\">\n                  <h4 class=\"uppercase\">\n                    <span class=\"person-name\">Flora Mykonos<\/span><br\/>\n                    <span class=\"person-title is-small thin-font op-7\">\n                                          <\/span>\n                  <\/h4>\n\t\t\t\t\t\n\nMykonos airport\r\nTelephone: +302289023509\n\n\n                <\/div>\n          <\/div>\n    <\/div>\n\n\t\n    \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-1862","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/pages\/1862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/comments?post=1862"}],"version-history":[{"count":9,"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/pages\/1862\/revisions"}],"predecessor-version":[{"id":2628,"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/pages\/1862\/revisions\/2628"}],"wp:attachment":[{"href":"https:\/\/c-potou.com\/fr\/wp-json\/wp\/v2\/media?parent=1862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}